{"id":1583,"date":"2022-06-14T05:02:59","date_gmt":"2022-06-14T05:02:59","guid":{"rendered":"https:\/\/old.skyhighdominicana.com\/?page_id=1583"},"modified":"2023-05-21T03:25:56","modified_gmt":"2023-05-21T03:25:56","slug":"politicas-cookies","status":"publish","type":"page","link":"https:\/\/old.skyhighdominicana.com\/en\/politicas-cookies\/","title":{"rendered":"Cookie Policies"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1583\" class=\"elementor elementor-1583\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3775d59 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3775d59\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fab38eb\" data-id=\"fab38eb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44049d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44049d1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0df13d\" data-id=\"a0df13d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-557e765 elementor-widget elementor-widget-text-editor\" data-id=\"557e765\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<header><\/header><div class=\"\"><div class=\"\"><p>En esta web se utilizan cookies de terceros y propias para conseguir que tengas una mejor experiencia de navegaci\u00f3n, puedas compartir contenido en redes sociales y para que podamos obtener estad\u00edsticas de los usuarios.<br \/><br \/>Puedes evitar la descarga de cookies a trav\u00e9s de la configuraci\u00f3n de tu navegador, evitando que las cookies se almacenen en su dispositivo.<br \/><br \/>Como propietario de este sitio web, te comunico que no utilizamos ninguna informaci\u00f3n personal procedente de cookies, tan s\u00f3lo realizamos estad\u00edsticas generales de visitas que no suponen ninguna informaci\u00f3n personal.<br \/><br \/>Es muy importante que leas la presente pol\u00edtica de cookies y comprendas que, si contin\u00faas navegando, consideraremos que aceptas su uso.<br \/><br \/>Seg\u00fan los t\u00e9rminos incluidos en el art\u00edculo 22.2 de la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico, si contin\u00faas navegando, estar\u00e1s prestando tu consentimiento para el empleo de los referidos mecanismos.<\/p><h3>Entidad Responsable<\/h3><p class=\"ng-binding\">La entidad responsable de la recogida, procesamiento y utilizaci\u00f3n de tus datos personales, en el sentido establecido por la Ley de Protecci\u00f3n de Datos Personales es la p\u00e1gina SKYhigh Dominicana, propiedad de SKYhigh Dominicana \u2013 Plaza Las Am\u00e9ricas 2do nivel 23B Av. Winston Churchill esq. Roberto Pastoriza \u200b.<\/p><h3>\u00bfQu\u00e9 son las cookies?<\/h3><p>Las cookies son un conjunto de datos que un servidor deposita en el navegador del usuario para recoger la informaci\u00f3n de registro est\u00e1ndar de Internet y la informaci\u00f3n del comportamiento de los visitantes en un sitio web. Es decir, se trata de peque\u00f1os archivos de texto que quedan almacenados en el disco duro del ordenador y que sirven para identificar al usuario cuando se conecta nuevamente al sitio web. Su objetivo es registrar la visita del usuario y guardar cierta informaci\u00f3n. Su uso es com\u00fan y frecuente en la web ya que permite a las p\u00e1ginas funcionar de manera m\u00e1s eficiente y conseguir una mayor personalizaci\u00f3n y an\u00e1lisis sobre el comportamiento del usuario.<\/p><h3>\u00bfQu\u00e9 tipos de cookies existen?<\/h3><p>Las cookies utilizadas en nuestro sitio web, son de sesi\u00f3n y de terceros, y nos permiten almacenar y acceder a informaci\u00f3n relativa al idioma, el tipo de navegador utilizado, y otras caracter\u00edsticas generales predefinidas por el usuario, as\u00ed como, seguir y analizar la actividad que lleva a cabo, con el objeto de introducir mejoras y prestar nuestros servicios de una manera m\u00e1s eficiente y personalizada.<br \/><br \/><\/p><p class=\"ng-binding\">Las cookies, en funci\u00f3n de su permanencia, pueden dividirse en cookies de sesi\u00f3n o permanentes. Las que expiran cuando el usuario cierra el navegador. Las que expiran en funci\u00f3n de cuando se cumpla el objetivo para el que sirven (por ejemplo, para que el usuario se mantenga identificado en los servicios de SKYhigh Dominicana) o bien cuando se borran manualmente.<\/p><p>\u00a0<\/p><table border=\"0\" width=\"100%\" cellpadding=\"15\"><tbody><tr><td>Nombre<\/td><td>Tipo<\/td><td>Caducidad<\/td><td>Finalidad<\/td><td>Clase<\/td><\/tr><tr><td>__utma<\/td><td>De Terceros (Google Analytics)<\/td><td>2 a\u00f1os<\/td><td>Se usa para distinguir usuarios y sesiones.<\/td><td>No Exenta<\/td><\/tr><tr><td>__utmb<\/td><td>De Terceros (Google Analytics)<\/td><td>30 minutos<\/td><td>Se usa para determinar nuevas sesiones o visitas<\/td><td>No Exenta<\/td><\/tr><tr><td>__utmc<\/td><td>De Terceros (Google Analytics)<\/td><td>Al finalizar la sesi\u00f3n<\/td><td>Se configura para su uso con Urchin<\/td><td>No Exenta<\/td><\/tr><tr><td>__utmz<\/td><td>De Terceros (Google Analytics)<\/td><td>6 meses<\/td><td>Almacena el origen o la campa\u00f1a que explica c\u00f3mo el usuario ha llegado hasta la p\u00e1gina web<\/td><td>No Exenta<\/td><\/tr><\/tbody><\/table><p class=\"ng-binding\">Adicionalmente, en funci\u00f3n de su objetivo, las cookies pueden clasificarse de la siguiente forma:<\/p><h3>Cookies de rendimiento<\/h3><p>Este tipo de Cookie recuerda sus preferencias para las herramientas que se encuentran en los servicios, por lo que no tiene que volver a configurar el servicio cada vez que usted visita. A modo de ejemplo, en esta tipolog\u00eda se incluyen: Ajustes de volumen de reproductores de v\u00eddeo o sonido. Las velocidades de transmisi\u00f3n de v\u00eddeo que sean compatibles con su navegador. Los objetos guardados en el \u201ccarrito de la compra\u201d en los servicios de e-commerce tales como tiendas.<\/p><h3>Cookies de geo-localizaci\u00f3n<\/h3><p>Estas cookies son utilizadas para averiguar en qu\u00e9 pa\u00eds se encuentra cuando se solicita un servicio. Esta cookie es totalmente an\u00f3nima, y s\u00f3lo se utiliza para ayudar a orientar el contenido a su ubicaci\u00f3n.<\/p><h3>Cookies de registro<\/h3><p>Las cookies de registro se generan una vez que el usuario se ha registrado o posteriormente ha abierto su sesi\u00f3n, y se utilizan para identificarle en los servicios con los siguientes objetivos:<\/p><p>Mantener al usuario identificado de forma que, si cierra un servicio, el navegador o el ordenador y en otro momento u otro d\u00eda vuelve a entrar en dicho servicio, seguir\u00e1 identificado, facilitando as\u00ed su navegaci\u00f3n sin tener que volver a identificarse. Esta funcionalidad se puede suprimir si el usuario pulsa la funcionalidad [cerrar sesi\u00f3n], de forma que esta cookie se elimina y la pr\u00f3xima vez que entre en el servicio el usuario tendr\u00e1 que iniciar sesi\u00f3n para estar identificado.<\/p><p>Comprobar si el usuario est\u00e1 autorizado para acceder a ciertos servicios, por ejemplo, para participar en un concurso.<\/p><p>Adicionalmente, algunos servicios pueden utilizar conectores con redes sociales tales como Facebook o Twitter. Cuando el usuario se registra en un servicio con credenciales de una red social, autoriza a la red social a guardar una Cookie persistente que recuerda su identidad y le garantiza acceso a los servicios hasta que expira. El usuario puede borrar esta Cookie y revocar el acceso a los servicios mediante redes sociales actualizando sus preferencias en la red social que espec\u00edfica.<\/p><h3>Cookies de anal\u00edticas<\/h3><p class=\"ng-binding\">Cada vez que un usuario visita un servicio, una herramienta de un proveedor externo genera una cookie anal\u00edtica en el ordenador del usuario. Esta cookie que s\u00f3lo se genera en la visita, servir\u00e1 en pr\u00f3ximas visitas a los servicios de SKYhigh Dominicana para identificar de forma an\u00f3nima al visitante. Los objetivos principales que se persiguen son:<\/p><p>Permitir la identificaci\u00f3n an\u00f3nima de los usuarios navegantes a trav\u00e9s de la cookie (identifica navegadores y dispositivos, no personas) y por lo tanto la contabilizaci\u00f3n aproximada del n\u00famero de visitantes y su tendencia en el tiempo.<br \/>Identificar de forma an\u00f3nima los contenidos m\u00e1s visitados y por lo tanto m\u00e1s atractivos para los usuarios Saber si el usuario que est\u00e1 accediendo es nuevo o repite visita.<\/p><p class=\"ng-binding\">Importante: Salvo que el usuario decida registrarse en un servicio de SKYhigh Dominicana, la cookie nunca ir\u00e1 asociada a ning\u00fan dato de car\u00e1cter personal que pueda identificarle. Dichas cookies s\u00f3lo ser\u00e1n utilizadas con prop\u00f3sitos estad\u00edsticos que ayuden a la optimizaci\u00f3n de la experiencia de los usuarios en el sitio.<\/p><h3>Cookies de publicidad<\/h3><p class=\"ng-binding\">Este tipo de cookies permiten ampliar la informaci\u00f3n de los anuncios mostrados a cada usuario an\u00f3nimo en los servicios de SKYhigh Dominicana. Entre otros, se almacena la duraci\u00f3n o frecuencia de visualizaci\u00f3n de posiciones publicitarias, la interacci\u00f3n con las mismas, o los patrones de navegaci\u00f3n y\/o comportamientos del usuario ya que ayudan a conformar un perfil de inter\u00e9s publicitario. De este modo, permiten ofrecer publicidad af\u00edn a los intereses del usuario.<\/p><h3>Cookies publicitarias de terceros<\/h3><p class=\"ng-binding\">Adem\u00e1s de la publicidad gestionada por las webs de SKYhigh Dominicana en sus servicios, las webs de SKYhigh Dominicana ofrecen a sus anunciantes la opci\u00f3n de servir anuncios a trav\u00e9s de terceros (\u201cAd-Servers\u201d). De este modo, estos terceros pueden almacenar cookies enviadas desde los servicios de SKYhigh Dominicana procedentes de los navegadores de los usuarios, as\u00ed como acceder a los datos que en ellas se guardan.<\/p><p class=\"ng-binding\">Las empresas que generan estas cookies tienen sus propias pol\u00edticas de privacidad. En la actualidad, las webs de SKYhigh Dominicana utilizan la plataforma Doubleclick (Google) para gestionar estos servicios. Para m\u00e1s informaci\u00f3n, acuda a<\/p><p><a href=\"http:\/\/www.google.es\/policies\/privacy\/ads\/#toc-doubleclick\">http:\/\/www.google.es\/policies\/privacy\/ads\/#toc-doubleclick<\/a>\u00a0y a\u00a0<a href=\"http:\/\/www.google.es\/policies\/privacy\/ads\/\">http:\/\/www.google.es\/policies\/privacy\/ads\/<\/a>.<\/p><h3>\u00bfC\u00f3mo puedo deshabilitar las cookies en mi navegador?<\/h3><p>Se pueden configurar los diferentes navegadores para avisar al usuario de la recepci\u00f3n de cookies y, si se desea, impedir su instalaci\u00f3n en el equipo. Asimismo, el usuario puede revisar en su navegador qu\u00e9 cookies tiene instaladas y cu\u00e1l es el plazo de caducidad de las mismas, pudiendo eliminarlas.<\/p><p>Para ampliar esta informaci\u00f3n consulte las instrucciones y manuales de su navegador:<\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Google Chrome:\u00a0<a href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=es\">https:\/\/support.google.com\/chrome\/answer\/95647?hl=es<\/a><\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Internet Explorer:\u00a0<a href=\"http:\/\/windows.microsoft.com\/es-es\/windows-vista\/cookies-frequently-asked-questions\">http:\/\/windows.microsoft.com\/es-es\/windows-vista\/cookies-frequently-asked-questions<\/a><\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Mozilla Firefox:\u00a0<a href=\"http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we%20\">http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we<\/a><\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Safari:\u00a0<a href=\"http:\/\/www.apple.com\/es\/privacy\/use-of-cookies\/%20\">http:\/\/www.apple.com\/es\/privacy\/use-of-cookies\/<\/a><\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Opera:\u00a0<a href=\"http:\/\/help.opera.com\/Windows\/11.50\/es-ES\/cookies.html\">http:\/\/help.opera.com\/Windows\/11.50\/es-ES\/cookies.html<\/a><\/p><p>Si desea dejar de ser seguido por Google Analytics visite:\u00a0<a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout\">http:\/\/tools.google.com\/dlpage\/gaoptout<\/a><\/p><h3>Actualizaciones y cambios en la pol\u00edtica de privacidad\/cookies<\/h3><p class=\"ng-binding\">Las webs de SKYhigh Dominicana pueden modificar esta Pol\u00edtica de Cookies en funci\u00f3n de exigencias legislativas, reglamentarias, o con la finalidad de adaptar dicha pol\u00edtica a las instrucciones dictadas por la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, por ello se aconseja a los usuarios que la visiten peri\u00f3dicamente.<\/p><p>Cuando se produzcan cambios significativos en esta Pol\u00edtica de Cookies, estos se comunicar\u00e1n a los usuarios bien mediante la web o a trav\u00e9s de correo electr\u00f3nico a los usuarios registrados.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>On this website, third-party and own cookies are used to ensure that you have a better browsing experience, you can share content on social networks and so that we can obtain user statistics. You can prevent the download of cookies through your browser settings, preventing cookies from being stored in\u2026 <a class=\"more-link\" href=\"https:\/\/old.skyhighdominicana.com\/en\/politicas-cookies\/\">continue reading <span class=\"screen-reader-text\">Cookie Policies<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"content-type":"","footnotes":""},"class_list":["post-1583","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edticas de Cookies - SKYhigh Aviation Services Dominicana S.A.<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edticas de Cookies - SKYhigh Aviation Services Dominicana S.A.\" \/>\n<meta property=\"og:description\" content=\"En esta web se utilizan cookies de terceros y propias para conseguir que tengas una mejor experiencia de navegaci\u00f3n, puedas compartir contenido en redes sociales y para que podamos obtener estad\u00edsticas de los usuarios. Puedes evitar la descarga de cookies a trav\u00e9s de la configuraci\u00f3n de tu navegador, evitando que las cookies se almacenen en&hellip; Continue reading Pol\u00edticas de Cookies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/old.skyhighdominicana.com\/en\/politicas-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"SKYhigh Aviation Services Dominicana S.A.\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-21T03:25:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/\",\"url\":\"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/\",\"name\":\"Pol\u00edticas de Cookies - SKYhigh Aviation Services Dominicana S.A.\",\"isPartOf\":{\"@id\":\"https:\/\/old.skyhighdominicana.com\/#website\"},\"datePublished\":\"2022-06-14T05:02:59+00:00\",\"dateModified\":\"2023-05-21T03:25:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/old.skyhighdominicana.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edticas de Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/old.skyhighdominicana.com\/#website\",\"url\":\"https:\/\/old.skyhighdominicana.com\/\",\"name\":\"SKYhigh Aviation Services Dominicana S.A.\",\"description\":\"Nacidos con la visi\u00f3n de aportar a la aviaci\u00f3n dominicana una empresa con sin\u00f3nimo de calidad\",\"publisher\":{\"@id\":\"https:\/\/old.skyhighdominicana.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/old.skyhighdominicana.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/old.skyhighdominicana.com\/#organization\",\"name\":\"SKYhigh Aviation Services Dominicana S.A.\",\"url\":\"https:\/\/old.skyhighdominicana.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/old.skyhighdominicana.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/old.skyhighdominicana.com\/wp-content\/uploads\/2023\/04\/SKYhigh-Logo-SKYhigh.svg\",\"contentUrl\":\"https:\/\/old.skyhighdominicana.com\/wp-content\/uploads\/2023\/04\/SKYhigh-Logo-SKYhigh.svg\",\"width\":411,\"height\":112,\"caption\":\"SKYhigh Aviation Services Dominicana S.A.\"},\"image\":{\"@id\":\"https:\/\/old.skyhighdominicana.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edticas de Cookies - SKYhigh Aviation Services Dominicana S.A.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Pol\u00edticas de Cookies - SKYhigh Aviation Services Dominicana S.A.","og_description":"En esta web se utilizan cookies de terceros y propias para conseguir que tengas una mejor experiencia de navegaci\u00f3n, puedas compartir contenido en redes sociales y para que podamos obtener estad\u00edsticas de los usuarios. Puedes evitar la descarga de cookies a trav\u00e9s de la configuraci\u00f3n de tu navegador, evitando que las cookies se almacenen en&hellip; Continue reading Pol\u00edticas de Cookies","og_url":"https:\/\/old.skyhighdominicana.com\/en\/politicas-cookies\/","og_site_name":"SKYhigh Aviation Services Dominicana S.A.","article_modified_time":"2023-05-21T03:25:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/","url":"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/","name":"Pol\u00edticas de Cookies - SKYhigh Aviation Services Dominicana S.A.","isPartOf":{"@id":"https:\/\/old.skyhighdominicana.com\/#website"},"datePublished":"2022-06-14T05:02:59+00:00","dateModified":"2023-05-21T03:25:56+00:00","breadcrumb":{"@id":"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/old.skyhighdominicana.com\/politicas-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/old.skyhighdominicana.com\/politicas-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/old.skyhighdominicana.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edticas de Cookies"}]},{"@type":"WebSite","@id":"https:\/\/old.skyhighdominicana.com\/#website","url":"https:\/\/old.skyhighdominicana.com\/","name":"SKYhigh Aviation Services Dominicana SA","description":"Born with the vision of contributing to Dominican aviation a company with a synonym of quality","publisher":{"@id":"https:\/\/old.skyhighdominicana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/old.skyhighdominicana.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/old.skyhighdominicana.com\/#organization","name":"SKYhigh Aviation Services Dominicana SA","url":"https:\/\/old.skyhighdominicana.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/old.skyhighdominicana.com\/#\/schema\/logo\/image\/","url":"https:\/\/old.skyhighdominicana.com\/wp-content\/uploads\/2023\/04\/SKYhigh-Logo-SKYhigh.svg","contentUrl":"https:\/\/old.skyhighdominicana.com\/wp-content\/uploads\/2023\/04\/SKYhigh-Logo-SKYhigh.svg","width":411,"height":112,"caption":"SKYhigh Aviation Services Dominicana S.A."},"image":{"@id":"https:\/\/old.skyhighdominicana.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/old.skyhighdominicana.com\/en\/wp-json\/wp\/v2\/pages\/1583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.skyhighdominicana.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/old.skyhighdominicana.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/old.skyhighdominicana.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/old.skyhighdominicana.com\/en\/wp-json\/wp\/v2\/comments?post=1583"}],"version-history":[{"count":3,"href":"https:\/\/old.skyhighdominicana.com\/en\/wp-json\/wp\/v2\/pages\/1583\/revisions"}],"predecessor-version":[{"id":7486,"href":"https:\/\/old.skyhighdominicana.com\/en\/wp-json\/wp\/v2\/pages\/1583\/revisions\/7486"}],"wp:attachment":[{"href":"https:\/\/old.skyhighdominicana.com\/en\/wp-json\/wp\/v2\/media?parent=1583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}